{"id":77,"count":1,"description":"","link":"https:\/\/buecher-books-libros.com\/es\/tag\/archaeologie\/","name":"Arch\u00e4ologie","slug":"archaeologie","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/tags\/77"}],"collection":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts?tags=77"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}