{"id":2057,"date":"2025-06-28T18:20:54","date_gmt":"2025-06-28T18:20:54","guid":{"rendered":"https:\/\/buecher-books-libros.com\/?p=2057"},"modified":"2025-07-05T04:36:42","modified_gmt":"2025-07-05T04:36:42","slug":"christoph-hein-das-narrenschiff","status":"publish","type":"post","link":"https:\/\/buecher-books-libros.com\/es\/h\/christoph-hein-das-narrenschiff\/","title":{"rendered":"Christoph Hein: Das Narrenschiff"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"865\" height=\"1024\" src=\"https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2025\/06\/IMG_3304-865x1024.jpeg\" alt=\"\" class=\"wp-image-2048\" srcset=\"https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2025\/06\/IMG_3304-865x1024.jpeg 865w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2025\/06\/IMG_3304-253x300.jpeg 253w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2025\/06\/IMG_3304-768x909.jpeg 768w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2025\/06\/IMG_3304-1298x1536.jpeg 1298w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2025\/06\/IMG_3304-1731x2048.jpeg 1731w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2025\/06\/IMG_3304-10x12.jpeg 10w\" sizes=\"(max-width: 865px) 100vw, 865px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Christoph Hein hat in vielen Romanen sein eigenes Leben, davon 40 Jahre in der DDR, und damit auch Zeitgeschichte aus Ost- und Westdeutschland verarbeitet. So u.a. in dem lesenswerten Roman \u201eUnterm Staub der Zeit. Eine Jugend im Schatten des Mauerbaus\u201c (2023). Mit seinem j\u00fcngsten Werk, dem 751-seitigen \u201eNarrenschiff\u201c, greift er zeitlich viel weiter aus.<\/p>\n\n\n\n<p>Der Roman beginnt mit dem Flug der Gruppe Ulbricht im April 1945 und nachfolgender Mitglieder des \u201eNationalkomitees Freies Deutschland\u201c von Moskau nach Berlin, um die kommunistische Macht\u00fcbernahme&nbsp;&nbsp;in der Sowjetischen Besatzungszone (SBZ) vorzubereiten und erstreckt sich bis zu den Anf\u00e4ngen der Wiedervereinigung. Dennoch reflektiert Hein nicht auf die \u201eStunde Null\u201c, sofern es in der Geschichte so etwas \u00fcberhaupt gibt.<\/p>\n\n\n\n<p>Jede der handelnden Personen bringt etwas aus ihrer Vorleben mit. Sei es die NS-Vergangenheit, seien es die Jahre in der kommunistischen Jugend, sei es das Moskauer oder das Exil im westlichen Ausland. Das kann Belastung und Motivation, oder beides sein.<\/p>\n\n\n\n<p>H\u00e4ufig wird die Frage nach dem autobiographischen Anteil eines Romans gestellt, und ebenso h\u00e4ufig vom Autor offengelassen. Nicht so Hein. In wenigen, eigens kursiv gedruckten Zeilen, stellt er klar, dass er sich nur f\u00fcr wenige dieser 751 Seiten nicht verb\u00fcrgen k\u00f6nne, ansonsten erz\u00e4hle er nur, \u201ewas ich mit eigenen Augen gesehen, mit eigenen Ohren geh\u00f6rt habe, wenn ich nur Personen schildere, die ich zu meiner Freude oder zu meinem Leidwesen pers\u00f6nlich kennenlernte, sie sch\u00e4tzen durfte oder f\u00fcrchten musste, die mir auf meinem Lebensweg behilflich waren oder mir Kn\u00fcppel zwischen die Beine warfen\u201c. Alles, so Hein, \u201eeine wahre Geschichte\u201c. So handelt es sich bei Kathinka beispielsweise um seine erste Frau.<\/p>\n\n\n\n<p>Der Roman konzentriert sich im Wesentlichen auf drei Personen und ihr Umfeld.<\/p>\n\n\n\n<p>Dr. Johannes Goretzka, in seiner Jugend NS-Anh\u00e4nger, bekehrte sich in der Kriegsgefangenschaft zum gl\u00fchenden Kommunisten und Stalin-Verehrer, im privaten Umgang ist kalt und unnahbar.<\/p>\n\n\n\n<p>Als fachlich hochqualifizierter Ingenieur und 180%iger Parteisoldat steht er kurz davor Minister zu werden. Er meint jedoch, aufgrund seiner bisherigen Verdienste in einer ihm wesentlich erscheinenden Fachfrage entgegen der Parteilinie auf seiner Meinung beharren zu k\u00f6nnen.<\/p>\n\n\n\n<p>Aufgrund seiner eigenen leidvollen Erfahrungen liest ihm Prof. Karsten Emser, Mitglied des ZK der SED, der ihn um Haaresbreite vor dem Parteiausschluss gerettet hat, die Leviten: \u201eMan darf sich irren, aber nie gegen die Partei. Und wenn die Partei sich irrt, machst du einen Fehler, wenn du diesen Irrtum nicht teilst. Man darf nie gegen die Partei Recht haben, denn sie allein hat immer recht.\u201c<\/p>\n\n\n\n<p>An Goretzka wird exemplarisch vorgef\u00fchrt, was es bedeutet, aufzusteigen, Parteidisziplin bis zur Selbstaufgabe zu \u00fcben, aber beim kleinsten Fehler oder einer behaupteten Abweichung tief zu st\u00fcrzen und pl\u00f6tzlich sozial isoliert und beruflich degradiert weiter leben zu m\u00fcssen. Und es ist schwer nachzuvollziehen, wie dieser Mann in seinem Kadavergehorsam verharrt, die Partei nach wie vor in Schutz nimmt und auf eine illusorische Rehabilitierung hofft. Aber da die Partei selbst \u00fcber den Tod hinaus entscheidet, wo (ehemals) f\u00fchrende Parteikader beerdigt werden, findet er nicht einmal seine letzte Ruhest\u00e4tte wie erhofft auf dem sogenannten Sozialistenfriedhof.<\/p>\n\n\n\n<p>Am beeindruckendsten erschien mir die Figur von Prof. Karsten Emser, die am detailliertesten und subtilsten geschildert, ja analysiert wird. Emser, wichtiger Mitarbeiter der KOMINTERN, der die Jahre im Moskauer Exil und die verschiedenen S\u00e4uberungswellen des stalinschen Terrors \u00fcberlebt hatte, R\u00fcckkehrer der ersten Nachkriegsstunde, offenbart seiner Frau erst in seinen letzten Lebensmonaten zumindest Teile seiner Erlebnisse und Leidensgeschichte. Dazu geh\u00f6rt sein Schweigen bei der Auslieferung seines besten Freundes an die Nazis und dessen Ermordung im KZ aufgrund des Hitler-Stalin-Paktes, eine kurze, aber eine der eindr\u00fccklichsten Passagen des Buches. Er wirft sich vor, zu oft geschwiegen zu haben, aus Angst, aus Feigheit: \u201eWir haben den Spiegel zerbrochen, um uns nicht selbst darin sehen zu m\u00fcssen\u201c.<\/p>\n\n\n\n<p>Emser sah von Gr\u00fcndung der DDR an, eines k\u00fcnstlich und gegen die Bev\u00f6lkerung geschaffenen, sp\u00e4ter dann im wahrsten Sinne des Wortes eingemauerten Staates, dessen \u00f6konomische Achillesferse und hegte erhebliche Zweifel daran, ob dieser Staat \u00f6konomisch und damit auch politisch langfristig eine \u00dcberlebenschance haben w\u00fcrde. Seine Zweifel werden zur Gewissheit und er leidet an seiner \u00dcberfl\u00fcssigkeit im ZK der SED, unternimmt aber nichts, weil er seine Professur nicht gef\u00e4hrden will, sein wichtigster Lebensinhalt.<\/p>\n\n\n\n<p>Als es gegen Hitler ging sah er sich auf der richtigen Seite der Geschichte. Aber diese Seite \u201everfinsterte sich, wurde rabenschwarz\u201c. Und nun wei\u00df er nicht mehr, wo er steht: \u201eVielleicht auf dem Deck eines Narrenschiffs\u2026Und wieder schweige ich. Schweige wie damals\u201c.<\/p>\n\n\n\n<p>Emser zieht eine verbitterte Lebensbilanz: \u201eIn Moskau war es eine schlimmere Zeit, viel schlimmer, aber die Hoffnungen, mit denen wir dann hier begannen, sie haben sich f\u00fcr mich zu einer Karikatur verzerrt\u201c.<\/p>\n\n\n\n<p>Die bedauernswerteste Figur scheint mir Prof. Benaja Kuckuck zu sein. Der international anerkannte Literaturwissenschaftler wurde eher als Betriebsunfall in der Vorkriegszeit in England Parteimitglied, und zahlte in den nachfolgenden Jahrzehnten f\u00fcr diese emotionale Entscheidung, getroffen wegen seines Hasses gegen Hitler und Franco, einen hohen beruflichen und pers\u00f6nlichen Preis. Er geht nach dem Krieg nach Deutschland zur\u00fcck, hofft auf eine versprochene Fortsetzung seiner Uni-Karriere, seine KP-Mitgliedschaft verhindert dies jedoch. Seine \u00dcbersiedlung in die DDR f\u00fchrt ebenfalls in eine Sackgasse, man verweigert ihm eine Professur, sein West-Exil spricht dagegen. Er endet als Abteilungsleiter f\u00fcr Kinderfilme und muss daf\u00fcr auf Anweisung der SED sogar in die liberale Blockpartei \u00fcbertreten, damit die pluralistische Fassade der \u201eNationalen Front\u201c gewahrt bleibt. Als versteckter Homosexueller findet er zwar einen Lebensgef\u00e4hrten. Aber berufliche Erf\u00fcllung sieht anders aus und er verpackt seine Verbitterung, Skepsis und Kritik in mehr oder weniger offene Ironie bis Sarkasmus und wandelt damit best\u00e4ndig am Rande des Kraters.<\/p>\n\n\n\n<p>Eher im Windschatten ihrer bedeutenden M\u00e4nner sind die Frauen in diesem Roman angesiedelt.<\/p>\n\n\n\n<p>Yvonne Lebinski geht als Witwe eines j\u00fcdischen Widerstandsk\u00e4mpfers mit ihrer Tochter Kathinka die Versorgungsehe mit einem weitgehend gef\u00fchllosen Ehemann und Stiefvater Johannes Goretzka ein, der sich den Minimalbestand an Empathie f\u00fcr den gemeinsamen Sohn aufhebt und sich vor allem beruflich und bis zur L\u00e4cherlichkeit als Parteisoldat auslebt.<\/p>\n\n\n\n<p>Kathinka leidet lange unter dieser Lieblosigkeit, findet aber ihren eigenen Weg, der schlie\u00dflich an der Seite ihres Mannes Rudolf in die Opposition f\u00fchrt.<\/p>\n\n\n\n<p>Yvonne selbst ist ein unpolitischer Mensch und tritt nur auf Druck ihres Mannes der Partei bei, da auch nur so ein ins Auge gefasster Arbeitsplatz erreichbar ist. Sie arrangiert sich mit dieser Situation, eine Scheidung kommt aus Statusgr\u00fcnden nicht in Betracht. Sie befreundet sich mit Rita Emser, die sehr viel bewu\u00dfter und \u00fcberzeugter in der Partei arbeitet, trotz der selbstkritischen Entwicklung ihres Mannes ist bei ihr aber keine parteiskeptische Haltung auszumachen.<\/p>\n\n\n\n<p>In dieser Geschichte m\u00fcssen sich alle irgendwie zum SED &#8211; Regime verhalten. Die Hauptpersonen dieses Romans stehen in unterschiedlichen Verh\u00e4ltnissen zum SED-Regime. Alle arbeiten in f\u00fchrenden und verantwortlichen Positionen, in die sie in ebenso unterschiedlichen Formen gelangt sind.<\/p>\n\n\n\n<p>&nbsp;Jede dieser Personen hat in allerdings sehr unterschiedlichem Ausma\u00df so ihre Fragen und Kritikpunkte, in eine offen kritische Position zum Regime bringt sich jedoch keine. Das ist auch gut nachvollziehbar. Die Lehren aus der kommunistischen Geschichte und Parteidiktatur waren eindeutig.<\/p>\n\n\n\n<p>Nicht nur die deutschen kommunistischen Parteikader wie ZK-Mitglied Emser hielten sich aufgrund ihrer pers\u00f6nlichen Erfahrungen mit abweichenden Auffassungen bedeckt und strikt an die Parteilinie, so oft diese auch wechseln mochte.<\/p>\n\n\n\n<p>&nbsp;Die Prozesse der Nachkriegszeit in der DDR, auch noch mit Todesurteilen, soweit offiziell bekannt, wurde das letzte im Juni 1981 (!) vollstreckt, die Niederschlagung des Volksaufstandes vom 17. Juni 1953 durch die Panzer des Gro\u00dfen Bruders Sowjetunion und die darauffolgende \u201ebr\u00fcderliche Hilfe\u201c in Ungarn 1956 oder bei der Niederwalzung des Prager Fr\u00fchlings 1968 machten jedem Einzelnen immer wieder deutlich, wohin Opposition f\u00fchren w\u00fcrde.<\/p>\n\n\n\n<p>F\u00fcr die DDR selbst war der Arbeiteraufstand am 17. Juni, nicht nur in Ost-Berlin, sondern in vielen Teilen der DDR, der dramatischste Wendepunkt: \u201eEs war nach dem gro\u00dfen Sturm eine gro\u00dfe Ruhe eingekehrt oder als habe sich vielmehr ein Mehltau aus Apathie und Depression \u00fcber die Stadt gelegt. Der Aufstand, der so massiv gebrochen wurde, hatte in eine Lethargie gef\u00fchrt, zu einer Bewusstseinsl\u00e4hmung der B\u00fcrger\u2026\u201c.<\/p>\n\n\n\n<p>Sich in F\u00fchrungsfunktionen auch auf nachgeordneter Ebene zu bewegen war ein permanenter Ritt auf der Rasierklinge. Wenn es nicht so ernst gewesen w\u00e4re, k\u00f6nnte man lachen, so bei der Schilderung der ideologischen Verrenkungsdebatten um die Produktion von Kinderfilmen. Interessant zu lesen, wie nach dem Mauerbau im Bereich der Kulturpolitik eine kurze Tauwetter-Periode einsetzte, die jedoch sehr schnell durch die SED-Hardliner auf dem \u201eKahlschlag-Plenum\u201c der SED von 1965 wieder in eine kulturelle Eiszeit r\u00fcckverwandelt wurde. Hinweis am Rande: Zu dieser Periode gibt es ein lesenswertes Buch von Gunnar Decker: \u201e1965. Der kurze Sommer der DDR.\u201c<\/p>\n\n\n\n<p>Beklemmend wird sp\u00fcrbar, wie die \u201eHaltungsfrage\u201c, d.h. die eigene Einstellung und das Verhalten zu Partei und Staatsmacht alle Bereiche des beruflichen wie privaten Lebens durchdringt und konditioniert. Dies f\u00fchrt zu vielen nicht nur gebeugten, sondern vielfach gebrochenen, zerbrochenen Biografien. Keiner, gleichg\u00fcltig wie stark sein \u201eGlaube\u201c an die Partei und die Ideologie war oder ist oder wie hoch er in der Partei- und Staatsnomenklatur gestiegen ist, kommt unbesch\u00e4digt aus diesem System heraus.<\/p>\n\n\n\n<p>So erkl\u00e4rt sich eine Gemeinsamkeit zwischen Emser, Kuckuck und Goretzka: Eine entt\u00e4uschte, ja verbitterte Lebensbilanz.<\/p>\n\n\n\n<p>Interessant ist, wie Hein, ohne den Begriff zu verwenden, aufzeigt, dass auch die \u201einnere Emigration\u201c kein homogenes Gebilde ist. Vielmehr gestaltet jede der Hauptpersonen auf sehr unterschiedliche Art und Weise ihre sehr spezifische Form einer inneren Emigration.<\/p>\n\n\n\n<p>Hein ist kritisch, benennt Opportunisten und Mitl\u00e4ufer: \u201eMan richtet sich ein\u201c. Er beschreibt, denn er will weder Verteidiger noch Richter seiner Figuren sein, er will sie verstehbar machen. Wobei Verstehen nicht bedeutet akzeptieren, billigen oder gar guthei\u00dfen.<\/p>\n\n\n\n<p>Zu diesem Verstehbarmachen geh\u00f6rt auch die unausgesprochene Frage, die sich jeder Leser vor dem Urteilen selbst stellen sollte, so hypothetisch diese auch ist: Wie h\u00e4tte man sich selbst verhalten? \u00dcberzeugt, verlogen, opportunistisch-angepasst, passiver Mitl\u00e4ufer, rebellisch, politisch oppositionell, oder w\u00e4re man in die innere Emigration abgetaucht?<\/p>\n\n\n\n<p>In einem weiteren Sinne, auch wenn Hein dies nicht direkt thematisiert, f\u00fchrt das auch zu der ber\u00fchmt-ber\u00fcchtigten These Adornos, wonach es kein richtiges Leben im falschen geben k\u00f6nne. Trotz aller damit verbundenen positiven Herausforderung, was die eigene Lebensgestaltung betrifft, erschien mir dieser Fundamentalismus eines durchweg gut alimentierten Uni-Profs schon immer wenig realit\u00e4tstauglich und im Kern anma\u00dfend.<\/p>\n\n\n\n<p>Hier d\u00fcrfte auch eines der Probleme der Wiedervereinigung liegen: Das Unverst\u00e4ndnis, oder zumindest die Schwierigkeit der Wessis, ich bin selbst einer, nachzuvollziehen, dass sich trotz der Unterdr\u00fcckung viele Menschen in der DDR einen \u201eInselbereich\u201c geschaffen hatten, in dem sie zufrieden waren.<\/p>\n\n\n\n<p>Dennoch, und daran sollte die DDR am Ende ma\u00dfgeblich scheitern, ging das Abw\u00e4gen, das Austarieren zwischen Hinnahme der allt\u00e4glichen Unterdr\u00fcckung und der Flucht hieraus ins private \u201eInseldasein\u201c immer h\u00e4ufiger, und das vor allem in der j\u00fcngeren Generation zu Ungunsten des SED-Regimes aus. Das Leben sollte stimmiger werden! Wer das wollte, den konnte das Regime auch durch Zwang nicht mehr zum Kuschen bringen. Dies war der N\u00e4hrboden f\u00fcr eine vielgestaltige Opposition.<\/p>\n\n\n\n<p>Eine Opposition, die auch und gerade in bislang systemtreuen Elternh\u00e4usern in der jungen und sehr viel kritischeren Generation entstand. Nicht weiter verwunderlich, wenn beispielsweise Beat-Musik als&nbsp;\u201eeine akustische Kriegsvorbereitung\u201c gilt, mit der \u201eder Westen die Entwicklung unserer Jugendlichen beeinflussen will\u201c und junge Menschen sagen: \u201eMan hat uns die Welt gestohlen\u201c.<\/p>\n\n\n\n<p>Die Hoffnung, \u201eman k\u00f6nne in diesem versteinerten Land die Steine zum Tanzen bringen\u201c, schwand immer mehr. Statt eines deutschen Gorbatschow trat als letzter Ausdruck der staatlich-institutionalisierten SED-DDR-Sackgasse Egon Krenz als Nachfolger Honeckers auf die B\u00fchne. Heins Urteil \u00fcber Krenz ist deutlich: \u201eEin Kerl, zu nichts bef\u00e4higt und zu allem f\u00e4hig\u201c.<\/p>\n\n\n\n<p>Das Buch ist voll von vielen spannenden und erhellenden und Episoden und Einzelszenen.<\/p>\n\n\n\n<p>Sehr packend ist die eindr\u00fcckliche und auf Augenzeugenberichten beruhende, und von der offiziellen Darstellung fundamental abweichende Schilderung der Absetzung Ulbrichts durch Honecker und seiner Verb\u00fcndeten, nach Hein \u201eim Grunde ein Staatsstreich\u201c.<\/p>\n\n\n\n<p>Zum Untergang des versteinerten SED-Regimes trug entscheidend die sich in ihren Anf\u00e4ngen aus vielen kleinen Gruppen und Initiativen entwickelnde Friedensbewegung bei, die mit den Friedensgebeten in der Leipziger Nikolai-Kirche schlie\u00dflich zum nationalen Katalysator der massiven Unzufriedenheit wurde und schlie\u00dflich zu den immer massiver werdenden Montagsdemonstrationen f\u00fchrten. Die signifikante Zunahme der Ausreiseantr\u00e4ge und die Flucht Tausender DDR-B\u00fcrger in bundesdeutsche Botschaften einiger Ostblock-Staaten zeigten, wie br\u00fcchig und akzeptanzlos die SED-Herrschaft geworden war. Die irrt\u00fcmliche Mauer\u00f6ffnung (\u201eSchabowskis Zettel\u201c) f\u00fchrte in wenigen Stunden zur Implosion eines Staates, ein eher seltenes Ereignis in der Geschichte.<\/p>\n\n\n\n<p>Hein sagte in einem Interview: \u201eVon der DDR wird nichts bleiben. Sie wird vergessen werden. Von der DDR sind zuallererst die Leute geblieben, aber die sterben gerade aus\u201c.<\/p>\n\n\n\n<p>&nbsp;Ich habe da meine Zweifel. Im R\u00fcckblick wird viel verkl\u00e4rt und ideologisch instrumentalisiert. Die Versuche der deutschen extremen Rechte, F\u00fchrerstaat und Teile der DDR-Vergangenheit in ein Amalgam eines neuen deutschen Autoritarismus einzuschmelzen sind deutlich erkennbar.&nbsp;&nbsp;<\/p>\n\n\n\n<p>Aber es bleibt hoffentlich die Erinnerung und vor allem die Erkenntnis, dass derartige menschenverachtende Systeme nicht f\u00fcr die Ewigkeit geschaffen sind, sondern das Freiheitsbed\u00fcrfnis der Menschen st\u00e4rker ist.&nbsp;<\/p>\n\n\n\n<p>Vielleicht generationsbedingt konnte ich das Buch nicht aus der Hand legen, in wenigen Tagen war es gelesen. Aber auch und gerade f\u00fcr j\u00fcngere Leser ist es zu empfehlen, da es einen Teil deutscher Nachkriegsgeschichte differenziert erlebbar macht. Trotz guter B\u00fccher von Eugen Ruge, Lutz Seiler und anderen, die diese Zeit verarbeiten: \u201eNarrenschiff\u201c ist f\u00fcr mich das beste Buch dieser Epoche.<\/p>\n\n\n\n<p>Ich w\u00fcnsche mir, dass dem 80j\u00e4hrigen Hein noch viele Lebensjahre und Kraft&nbsp;&nbsp;bleiben, um auch die Entwicklung nach dem Fall der Mauer in dem wiedervereinigten Deutschland zu beschreiben.<\/p>\n\n\n\n<p>Hein thematisiert aus der Anfangszeit der Wiedervereinigung vor allem das Problem der R\u00fcck\u00fcbertragung von Eigentum.&nbsp;Es gibt jedoch eine F\u00fclle von Einzelaspekten und Entwicklungen, von den Dimensionen der Stasi-Krake (rund 290 000 offizielle und informelle Mitarbeiter),&nbsp;&nbsp;die selbst Ehepartner aufeinander ansetze, bis hin zu den&nbsp;vielf\u00e4ltigen Probleme des Zusammenwachsens nicht nur in wirtschaftlicher Hinsicht, sondern gerade auch mit Blick auf das Aufeinanderprallen unterschiedlicher sozialer und politischer Sozialisierungen, die bis heute nicht \u00fcberwunden zu sein scheinen.<\/p>\n\n\n\n<p>Dies und viel mehr wartet auf einen \u00fcberzeugenden literarischen Chronisten. Christoph Hein ist so einer!<\/p>\n\n\n\n<p><strong>Christoph Hein<\/strong>: <strong>Das Narrenschiff<\/strong><\/p>\n\n\n\n<p>Suhrkamp, ISBN: 978-3-518-43226-6<\/p>\n<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger\" title=\"\" data-post-id=\"2057\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n                <\/a>\r\n    <span class=\"pld-like-count-wrap pld-count-wrap\">    <\/span>\r\n<\/div><div class=\"pld-dislike-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-dislike-trigger pld-like-dislike-trigger\" title=\"\" data-post-id=\"2057\" data-trigger-type=\"dislike\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                        <i class=\"fas fa-thumbs-down\"><\/i>\r\n                <\/a>\r\n    <span class=\"pld-dislike-count-wrap pld-count-wrap\"><\/span>\r\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Christoph Hein hat in vielen Romanen sein eigenes Leben, davon 40 Jahre in der DDR, und damit auch Zeitgeschichte aus Ost- und Westdeutschland verarbeitet. So u.a. in dem lesenswerten Roman \u201eUnterm Staub der Zeit. Eine Jugend im Schatten des Mauerbaus\u201c (2023). Mit seinem j\u00fcngsten Werk, dem 751-seitigen \u201eNarrenschiff\u201c, greift er zeitlich viel weiter aus. Der Roman beginnt mit dem Flug der Gruppe Ulbricht im April 1945 und nachfolgender Mitglieder des \u201eNationalkomitees Freies Deutschland\u201c von Moskau nach Berlin, um die kommunistische Macht\u00fcbernahme&nbsp;&nbsp;in der Sowjetischen Besatzungszone (SBZ) vorzubereiten und erstreckt sich bis zu den Anf\u00e4ngen der Wiedervereinigung. Dennoch reflektiert Hein nicht auf die \u201eStunde Null\u201c, sofern es in der Geschichte so etwas \u00fcberhaupt gibt. Jede der handelnden Personen bringt etwas aus ihrer Vorleben mit. Sei es die NS-Vergangenheit, seien es die Jahre in der kommunistischen Jugend, sei es das Moskauer oder das Exil im westlichen Ausland. Das kann Belastung und Motivation, oder beides sein. H\u00e4ufig wird die Frage nach dem autobiographischen Anteil eines Romans gestellt, und ebenso h\u00e4ufig vom Autor offengelassen. Nicht so Hein. In wenigen, eigens kursiv gedruckten Zeilen, stellt er klar, dass er sich nur f\u00fcr wenige dieser 751 Seiten nicht verb\u00fcrgen k\u00f6nne, ansonsten erz\u00e4hle er nur, \u201ewas ich mit eigenen Augen gesehen, mit eigenen Ohren geh\u00f6rt habe, wenn ich nur Personen schildere, die ich zu meiner Freude oder zu meinem Leidwesen pers\u00f6nlich kennenlernte, sie sch\u00e4tzen durfte oder f\u00fcrchten musste, die mir auf meinem Lebensweg behilflich waren oder mir Kn\u00fcppel zwischen die Beine warfen\u201c. Alles, so Hein, \u201eeine wahre Geschichte\u201c. So handelt es sich bei Kathinka beispielsweise um seine erste Frau. Der Roman konzentriert sich im Wesentlichen auf drei Personen und ihr Umfeld. Dr. Johannes Goretzka, in seiner Jugend NS-Anh\u00e4nger, bekehrte sich in der Kriegsgefangenschaft zum gl\u00fchenden Kommunisten und Stalin-Verehrer, im privaten Umgang ist kalt und unnahbar. Als fachlich hochqualifizierter Ingenieur und 180%iger Parteisoldat steht er kurz davor Minister zu werden. Er meint jedoch, aufgrund seiner bisherigen Verdienste in einer ihm wesentlich erscheinenden Fachfrage entgegen der Parteilinie auf seiner Meinung beharren zu k\u00f6nnen. Aufgrund seiner eigenen leidvollen Erfahrungen liest ihm Prof. Karsten Emser, Mitglied des ZK der SED, der ihn um Haaresbreite vor dem Parteiausschluss gerettet hat, die Leviten: \u201eMan darf sich irren, aber nie gegen die Partei. Und wenn die Partei sich irrt, machst du einen Fehler, wenn du diesen Irrtum nicht teilst. Man darf nie gegen die Partei Recht haben, denn sie allein hat immer recht.\u201c An Goretzka wird exemplarisch vorgef\u00fchrt, was es bedeutet, aufzusteigen, Parteidisziplin bis zur Selbstaufgabe zu \u00fcben, aber beim kleinsten Fehler oder einer behaupteten Abweichung tief zu st\u00fcrzen und pl\u00f6tzlich sozial isoliert und beruflich degradiert weiter leben zu m\u00fcssen. Und es ist schwer nachzuvollziehen, wie dieser Mann in seinem Kadavergehorsam verharrt, die Partei nach wie vor in Schutz nimmt und auf eine illusorische Rehabilitierung hofft. Aber da die Partei selbst \u00fcber den Tod hinaus entscheidet, wo (ehemals) f\u00fchrende Parteikader beerdigt werden, findet er nicht einmal seine letzte Ruhest\u00e4tte wie erhofft auf dem sogenannten Sozialistenfriedhof. Am beeindruckendsten erschien mir die Figur von Prof. Karsten Emser, die am detailliertesten und subtilsten geschildert, ja analysiert wird. Emser, wichtiger Mitarbeiter der KOMINTERN, der die Jahre im Moskauer Exil und die verschiedenen S\u00e4uberungswellen des stalinschen Terrors \u00fcberlebt hatte, R\u00fcckkehrer der ersten Nachkriegsstunde, offenbart seiner Frau erst in seinen letzten Lebensmonaten zumindest Teile seiner Erlebnisse und Leidensgeschichte. Dazu geh\u00f6rt sein Schweigen bei der Auslieferung seines besten Freundes an die Nazis und dessen Ermordung im KZ aufgrund des Hitler-Stalin-Paktes, eine kurze, aber eine der eindr\u00fccklichsten Passagen des Buches. Er wirft sich vor, zu oft geschwiegen zu haben, aus Angst, aus Feigheit: \u201eWir haben den Spiegel zerbrochen, um uns nicht selbst darin sehen zu m\u00fcssen\u201c. Emser sah von Gr\u00fcndung der DDR an, eines k\u00fcnstlich und gegen die Bev\u00f6lkerung geschaffenen, sp\u00e4ter dann im wahrsten Sinne des Wortes eingemauerten Staates, dessen \u00f6konomische Achillesferse und hegte erhebliche Zweifel daran, ob dieser Staat \u00f6konomisch und damit auch politisch langfristig eine \u00dcberlebenschance haben w\u00fcrde. Seine Zweifel werden zur Gewissheit und er leidet an seiner \u00dcberfl\u00fcssigkeit im ZK der SED, unternimmt aber nichts, weil er seine Professur nicht gef\u00e4hrden will, sein wichtigster Lebensinhalt. Als es gegen Hitler ging sah er sich auf der richtigen Seite der Geschichte. Aber diese Seite \u201everfinsterte sich, wurde rabenschwarz\u201c. Und nun wei\u00df er nicht mehr, wo er steht: \u201eVielleicht auf dem Deck eines Narrenschiffs\u2026Und wieder schweige ich. Schweige wie damals\u201c. Emser zieht eine verbitterte Lebensbilanz: \u201eIn Moskau war es eine schlimmere Zeit, viel schlimmer, aber die Hoffnungen, mit denen wir dann hier begannen, sie haben sich f\u00fcr mich zu einer Karikatur verzerrt\u201c. Die bedauernswerteste Figur scheint mir Prof. Benaja Kuckuck zu sein. Der international anerkannte Literaturwissenschaftler wurde eher als Betriebsunfall in der Vorkriegszeit in England Parteimitglied, und zahlte in den nachfolgenden Jahrzehnten f\u00fcr diese emotionale Entscheidung, getroffen wegen seines Hasses gegen Hitler und Franco, einen hohen beruflichen und pers\u00f6nlichen Preis. Er geht nach dem Krieg nach Deutschland zur\u00fcck, hofft auf eine versprochene Fortsetzung seiner Uni-Karriere, seine KP-Mitgliedschaft verhindert dies jedoch. Seine \u00dcbersiedlung in die DDR f\u00fchrt ebenfalls in eine Sackgasse, man verweigert ihm eine Professur, sein West-Exil spricht dagegen. Er endet als Abteilungsleiter f\u00fcr Kinderfilme und muss daf\u00fcr auf Anweisung der SED sogar in die liberale Blockpartei \u00fcbertreten, damit die pluralistische Fassade der \u201eNationalen Front\u201c gewahrt bleibt. Als versteckter Homosexueller findet er zwar einen Lebensgef\u00e4hrten. Aber berufliche Erf\u00fcllung sieht anders aus und er verpackt seine Verbitterung, Skepsis und Kritik in mehr oder weniger offene Ironie bis Sarkasmus und wandelt damit best\u00e4ndig am Rande des Kraters. Eher im Windschatten ihrer bedeutenden M\u00e4nner sind die Frauen in diesem Roman angesiedelt. Yvonne Lebinski geht als Witwe eines j\u00fcdischen Widerstandsk\u00e4mpfers mit ihrer Tochter Kathinka die Versorgungsehe mit einem weitgehend gef\u00fchllosen Ehemann und Stiefvater Johannes Goretzka ein, der sich den Minimalbestand an Empathie f\u00fcr den gemeinsamen Sohn aufhebt und sich vor allem beruflich und bis zur L\u00e4cherlichkeit als Parteisoldat auslebt. Kathinka leidet lange unter dieser Lieblosigkeit, findet aber ihren eigenen Weg, der schlie\u00dflich an der Seite ihres Mannes Rudolf in die Opposition f\u00fchrt. Yvonne selbst ist ein unpolitischer Mensch und tritt nur auf Druck ihres Mannes der<\/p>","protected":false},"author":1,"featured_media":2048,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[140],"class_list":["post-2057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-h","tag-christophhein-dasnarrenschiff-suhrkamp-ddr-sedregime-tbr-bookstagram"],"_links":{"self":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/2057"}],"collection":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/comments?post=2057"}],"version-history":[{"count":3,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/2057\/revisions"}],"predecessor-version":[{"id":2060,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/2057\/revisions\/2060"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/media\/2048"}],"wp:attachment":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/media?parent=2057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/categories?post=2057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/tags?post=2057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}