{"id":1896,"date":"2024-10-31T22:32:25","date_gmt":"2024-10-31T22:32:25","guid":{"rendered":"https:\/\/buecher-books-libros.com\/?p=1896"},"modified":"2024-11-03T04:14:12","modified_gmt":"2024-11-03T04:14:12","slug":"ruth-hoffmann-das-deutsche-alibi-mythos-stauffenberg-attentat-2","status":"publish","type":"post","link":"https:\/\/buecher-books-libros.com\/es\/h\/ruth-hoffmann-das-deutsche-alibi-mythos-stauffenberg-attentat-2\/","title":{"rendered":"Ruth Hoffmann: Das deutsche Alibi &#8211; Mythos &#8222;Stauffenberg-Attentat&#8220;"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"958\" src=\"https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/10\/IMG_6819-1024x958.jpeg\" alt=\"\" class=\"wp-image-1890\" srcset=\"https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/10\/IMG_6819-1024x958.jpeg 1024w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/10\/IMG_6819-300x281.jpeg 300w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/10\/IMG_6819-768x718.jpeg 768w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/10\/IMG_6819-1536x1436.jpeg 1536w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/10\/IMG_6819-2048x1915.jpeg 2048w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/10\/IMG_6819-13x12.jpeg 13w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Ich will mit einem \u201eBekenntnis\u201c beginnen. F\u00fcr mich waren als Sch\u00fcler Stauffenberg und die Beteiligten Helden. M\u00e4nner, die unter Einsatz ihres Lebens versucht hatten, einen der gr\u00f6\u00dften Verbrecher der Menschheitsgeschichte zu beseitigen, dabei scheiterten, und dennoch Gro\u00dfes und Beispielhaftes getan hatten. In diese Reihe geh\u00f6rten f\u00fcr mich auch die Geschwister Scholl und ihre Mitstreiter der \u201eWei\u00dfen Rose\u201c, \u201eder einsame Attent\u00e4ter\u201c (so ein Biographie &#8211; nTitel) Georg Elser oder der beeindruckende Dietrich Bonhoeffer, dessen wenige Monate vor seiner Hinrichtung in Pl\u00f6tzensee verfasstes Gebet \u201eVon guten M\u00e4chten\u201c mich bis heute begleitet.<\/p>\n\n\n\n<p>Wie h\u00e4tte Deutschland diese Menschen gebraucht!<\/p>\n\n\n\n<p>Sie waren und sind vermutlich bis heute f\u00fcr Viele die bekanntesten Pers\u00f6nlichkeiten des Widerstandes gegen Hitler.<\/p>\n\n\n\n<p>Je mehr man las, desto mehr erfuhr man jedoch \u00fcber die Breite des Widerstandes, die sehr unterschiedliche Herkunft von sich dem Regime entgegenstellenden Menschen, ihre Denkweise, ihre Motivationen, ihre Hoffnungen, ihre Ziele, ihre Erfolge, ihr Scheitern, ihr Sterben oder auch ihr \u00dcberleben. Zu meinen ersten beeindruckenden Leseerlebnissen z\u00e4hlt das Buch von Peter Hoffmann (Widerstand-Staatsstreich-Attentat), das mich regelrecht in Bann geschlagen hat.<\/p>\n\n\n\n<p>\u00dcber die Jahre erarbeitete die Forschung neue Erkenntnisse, schuf Raum f\u00fcr differierende Interpretationsans\u00e4tze und multiple Schwerpunktsetzungen.<\/p>\n\n\n\n<p>Insbesondere der Blick auf die milit\u00e4rischen Widerst\u00e4ndler, ihr Herkommen, ihre Denkungsart oder ihre anf\u00e4ngliche N\u00e4he zum nationalsozialistischen Regime wurde kritischer und erm\u00f6glichte ein immer realistischeres Bild der handelnden Personen und der Umst\u00e4nde.<br>Die Verfasserin ist beileibe nicht die erste, die Hand an den \u201eMythos\u201c legt. Ich verweise nur auf die hervorragende Biographie Stauffenbergs von Thomas Karlauf (2019).<br>Es entwickelte sich bei mir fr\u00fch ein Bewusstsein daf\u00fcr, dass es nicht immer nur die \u201eGro\u00dftaten\u201c waren, die erinnerungsw\u00fcrdig und beispielhaft sind. So setzte Hans Fallada in seinem 1947 erschienenem und heute noch lesenswerten Roman \u201eJeder stirbt f\u00fcr sich allein\u201c dem Ehepaar Hampel ein Denkmal. Die Biographie der deutschen Kommunistin Hertha Gordon-Walcher (\u201eBittere Brunnen\u201c), 2023 mit dem Preis der Leipziger Buchmesse ausgezeichnet, ist ein j\u00fcngstes Beispiel von in diesen Kontext geh\u00f6renden Lebensl\u00e4ufen.<\/p>\n\n\n\n<p>Das Thema l\u00e4sst die Deutschen offensichtlich nicht los, und das ist gut so.<\/p>\n\n\n\n<p>Die Geschichte des Widerstandes gegen Hitler d\u00fcrfte weitgehend erforscht sein. Wer sich \u00fcber die Jahre etwas intensiver mit dem Thema besch\u00e4ftigt hat, wird in \u201eDas deutsche Alibi\u201c nichts umst\u00fcrzend Neues finden. Aber es ist gut und wichtig, diesen Teil deutscher Geschichte f\u00fcr jede Generation immer wieder aufzugreifen und zu erz\u00e4hlen. Dies bietet die Chance, diesen Teil deutscher Geschichte an aktuelle Entwicklungen und Herausforderungen r\u00fcckzukoppeln. Raum f\u00fcr (neue) Interpretationen bleibt immer.<\/p>\n\n\n\n<p>Nun kann man, so der Ansatz des Buches, auch auf der Basis von reiner Quellenauswertung, d.h. der fachlichen und wissenschaftlichen Arbeit anderer, ein interessantes, anregendes Sachbuch mit neuen Erkenntnissen oder Interpretationsans\u00e4tzen schreiben. \u201eDas deutsche Alibi\u201c f\u00e4llt jedoch nicht in diese Kategorie.<\/p>\n\n\n\n<p>Zwar filtriert die Verfasserin aus ihrer Literaturschau eine ganze Reihe von zutreffenden, wenn auch bekannten Informationen heraus. Sei es die halbherzige und sp\u00e4te Aufarbeitung des Nationalsozalismus in der Fr\u00fchphase der Bundesrepublik, Schicksale wie die von Fritz Bauer, der sich um die Strafverfolgung von Nazi-Verbrechern verdient machte oder die Verengung der Widerstandsrezeption auf den milit\u00e4rischen Widerstand.<\/p>\n\n\n\n<p>Dennoch tat ich mir schwer mit diesem Buch. Aber nicht, weil es mir inhaltlich substantiell nichts Neues brachte. Es sind die Verallgemeinerungen, die Einseitigkeiten, offensichtliche Voreingenommenheiten, das Undifferenzierte, die Ausblendungen, eine vielfach allzu simple Argumentationsweise, das oftmals analytisch Unterkomplexe, die aufsto\u00dfen.<\/p>\n\n\n\n<p>Ich will mich auf einige wesentliche Kritikpunkte beschr\u00e4nken.<\/p>\n\n\n\n<ol class=\"wp-block-list\">\n<li>\u201eLinker\u201c und sonstiger Widerstand<\/li>\n<\/ol>\n\n\n\n<p>Die Verfasserin kritisiert, dass der \u201elinke Widerstand\u201c nicht hinreichend ber\u00fccksichtigt wurde und wird. Das traf sicherlich vor allem in den Anfangsjahren der Bundesrepublik zu und wurde der Geschichte und dem Blutzoll, den viele von der politischen Linken zahlen mussten, nicht gerecht.<\/p>\n\n\n\n<p>Ich habe den gr\u00f6\u00dften Respekt vor dem Mut und der Haltung der Sozialdemokraten, die meisten kommunistischen Abgeordneten waren bereits verhaftet oder auf der Flucht, die im Reichstag gegen das Erm\u00e4chtigungsgesetz Hitlers gestimmt haben. Der Satz des Sozialdemokraten Otto Wels in seiner Rede am 23. M\u00e4rz 1933: \u201eFreiheit und Leben kann man uns nehmen, die Ehre nicht\u201c, hat seinen Platz in der deutschen Geschichte.<\/p>\n\n\n\n<p>Weitgehend zutreffend ist auch, dass in der \u00f6ffentlichen Perzeption \u00fcber viele Jahre der 20. Juli dominierte und viele andere Gruppen und Widerstandsformen \u00fcberlagerte. Wobei die \u201eWeisse Rose\u201c der Geschwister Scholl, sehr fr\u00fch ebenfalls ein markanter \u201eErinnerungsort\u201c der Widerstandsgeschichte, nun nicht dem milit\u00e4risch-adligen Widerstand zuzurechnen ist.<br>Dabei gab es \u201eTausende andere Mutige, die viele Jahre vor dem 20. Juli 1944 ihr Leben f\u00fcr das riskiert hatten, was sie f\u00fcr richtig hielten\u201c. Dem ist nur zuzustimmen.<br>Aber standen diese Gegner wirklich nur links, im Ernst?<\/p>\n\n\n\n<p>Es gab beispielsweise auch Politiker der katholischen Zentrumspartei ebenso wie aus anderen b\u00fcrgerlichen Parteien oder ziviligesellschaftlichen Organisationen, die im Widerstand waren, in Gef\u00e4ngnissen und Konzentrationslagern sa\u00dfen oder zu Tode gekommen sind.<\/p>\n\n\n\n<p>Skurril wird es, wenn die Verfasserin Kardinal H\u00f6ffner vorwirft, in einer Rede zum 8. Mai nichts zum katholischen Widerstand gesagt zu haben. Das w\u00e4re doch die Gelegenheit gewesen, in ihrem Buch ein kleines Kapitel darauf zu verwenden. Aber halt, der erste Widerstand kam ja nur von \u201elinks\u201c. Ein Pater Alfred Delp, ein Pater Rupert Mayer oder ein Andreas Hermes, um nur drei Namen zu nennen, finden sich daher im Personenverzeichnis dieses Buches nicht. Es sind solche undifferenzierten Verengungen, die ver\u00e4rgern und ein unzutreffendes, weil unvollst\u00e4ndiges Bild zeichnen.<\/p>\n\n\n\n<ol start=\"2\" class=\"wp-block-list\">\n<li>\u201eWiderstand\u201c \u2013 Messen mit doppeltem Massstab<\/li>\n<\/ol>\n\n\n\n<p>Ein zentrales Problem besteht im Verst\u00e4ndnis des Begriffes \u201eWiderstand\u201c.<\/p>\n\n\n\n<p>Ich will hier gar nicht in die Debatte einsteigen, welche Formen von Widerstand es geben mag. Es geht im Kern darum, gegen was oder wen Widerstand geleistet wurde, im Falle der Nazis gegen eine der schlimmsten Diktaturen in der Menschheitsgeschichte.<\/p>\n\n\n\n<p>Vor diesem Hintergrund sollte man in der Lage sein, sich gegen den Missbrauch des Begriffs \u201eWiderstand\u201c durch die Studentenbewegung 1968 zu wenden, die meinte, diesen Begriff f\u00fcr ihren Kampf gegen ein \u201efaschistisches Nachkriegsdeutschland\u201c okkupieren zu k\u00f6nnen.<\/p>\n\n\n\n<p>Diese mangelnde Differenzierung beim \u201eWogegen\u201c setzt sich dann fort bei der Debatte des \u201eWof\u00fcr\u201c Widerstand geleistet wurde.<\/p>\n\n\n\n<p>Ich habe vor jedem den tiefsten Respekt, der sich wie aktiv auch immer gegen das Nazi-Regime gestellt hat. Da spielt es f\u00fcr mich keine Rolle, ob jemand Kommunist, Gewerkschafter, Liberaler oder katholischer oder evangelischer Christ oder sonst was war.<\/p>\n\n\n\n<p>Dies umso mehr, als uns \u201eNachgeborenen\u201c etwas mehr Demut gut zu Gesicht st\u00fcnde, denn keiner von uns wei\u00df, wie er selbst sich in solchen Zeiten verhalten h\u00e4tte. Die wenigsten sind zum Helden geboren.<\/p>\n\n\n\n<p>Dies darf aber nicht verbieten zu fragen, was denn die Widerst\u00e4ndler an Stelle der Hitler-Diktatur wollten, d.h. \u201ewof\u00fcr\u201c Widerstand geleistet wurde. Dagegen wendet sich die Verfasserin jedoch mit H\u00e4nden und F\u00fc\u00dfen.<br>So geht der kritische Blick der Verfasserin vor allem in Richtung des milit\u00e4risch-adligen Widerstandes.<br>Unbestritten ist: Die Gruppe um den 20. Juli hatte keinen Verfassungsentwurf erarbeitet, den der Parlamentarische Rat 1948 dann einfach abgenickt h\u00e4tte. Viele aus den verschiedenen Verschw\u00f6rer- \/ Widerstandskreisen waren inhaltlich auf der Suche und ja, sie waren nicht die Demokraten der Bundesrepublik, und der Klimawandel war im \u00dcbrigen auch noch nicht ihr Thema. Dennoch ist es zu undifferenziert, dem adlig-milit\u00e4rischen Widerstand eine zu gering ausgepr\u00e4gte und nicht das Grundgesetz oder die demokratische Struktur Nachkriegsdeutschlands detailliert vorwegnehmende Demokratieorientierung vorzuhalten.<\/p>\n\n\n\n<p>Denn: Auch wenn die Demokratieerfahrung mit der Weimarer Republik f\u00fcr viele nicht unbedingt positiv war, ist eines klar: Sie wollten keine Diktatur! Sie wollten einen Rechtsstaat! Sie wollten die Achtung der Menschenw\u00fcrde! Sie hatten die Lektion gelernt!<\/p>\n\n\n\n<p>Und es gab viele Ans\u00e4tze und Versuche, unter h\u00f6chst gef\u00e4hrlichen Bedingungen zu diskutieren und Antworten f\u00fcr die Zeit nach Hitler zu finden. Der Kreisauer Kreis, der daran gearbeitet hat, die politische Spaltung des Christentums zu \u00fcberwinden und ebenfalls seinen Blutzoll zahlen musste, ist nur ein herausragendes Beispiel.<\/p>\n\n\n\n<p>Vieles von diesen Debatten und Werten findet sich im Grundgesetz wieder. Der Vorwurf einer \u201egerade von konservativen Politikern so gern herbeikonstruierte(n) Verbindungslinie zwischen dem deutschen Widerstand und dem Grundgesetz\u201c ist daher ebenfalls zu undifferenziert greift zu kurz.<\/p>\n\n\n\n<p>So berechtigt die Frage, besser gesagt, in diesem Buch der Vorwurf, an den adlig-milit\u00e4rischen Widerstand ist, wie lange man zumindest in Teilen dem NS-Regime nahegestanden habe und wie sp\u00e4t und warum man sich schliesslich zum Widerstand entschlossen habe ist, so berechtigt erscheint doch die Frage an den kommunistischen Teil des Widerstandes, welches System denn w\u00e4hrend des Widerstandes unterst\u00fctzt wurde und was an die Stelle der Nazi-Diktatur treten sollte.<\/p>\n\n\n\n<p>Dies wird von der Verfasserin systematisch abgeblockt. Der \u201elinke\u201c Widerstand rechtfertigt alles, \u00fcberdeckt alles! Man war ja \u201eKind seiner Zeit\u201c. Wenn bei Stauffenberg und anderen ihre anf\u00e4ngliche N\u00e4he zum Naziregime und ihre sp\u00e4te Bekehrung kritisiert wird, dann muss jedoch der Hinweis erlaubt sein, dass viele der kommunistischen linken Widerst\u00e4ndler eine vergleichbare Bekehrung nie durchgemacht haben.<\/p>\n\n\n\n<p>Um es zu wiederholen: Das schm\u00e4lert den kommunistischen Widerstand nicht und achtet den Blutzoll nicht gering, der entrichtet wurde.<\/p>\n\n\n\n<p>Aber in dem Moment, in dem es um die demokratische Fortsetzungsgeschichte geht bedarf es einer differenzierten Sicht auf Gruppierungen und ihre Zielsetzungen.<\/p>\n\n\n\n<p>Und die Kommunisten verbargen ja auch nicht, was sie wollten: Die \u201eDiktatur des Proletariats\u201c und dem leuchtenden Vorbild des gro\u00dfen Bruders \u201eSowjetunion\u201c und der KPdSU folgen. Das war die Blaupause f\u00fcr die kommunistische Vorstellung des Nachkriegsdeutschlands, wie sie ja dann in der DDR auch brutal umgesetzt wurde.<\/p>\n\n\n\n<p>Ein Walter Ulbricht, Erich Honecker oder ein Mielke geh\u00f6ren f\u00fcr mich nicht in eine demokratische deutsche Tradition. Ebensowenig wie andere Handlanger des Stalinismus, die genau wussten, wem sie wof\u00fcr die Hand reichten. Will man im Ernst behaupten, die im Moskauer Hotel Lux sitzenden deutschen wie internationalen Kommunistenf\u00fchrer h\u00e4tten an der Errichtung (deutscher) demokratischer Verh\u00e4ltnisse gearbeitet?<\/p>\n\n\n\n<p>In dieses Narrativ, oder sollte man sagen \u201eStrategie\u201c der Entkopplung zwischen \u201eWogegen\u201c und \u201eWof\u00fcr\u201c des Widerstandes f\u00fcgt sich dann auch Folgendes gut ein.<br>Wohl bezogen auf die 50er und beginnenden 60er Jahre spricht die Verfasserin dann schlie\u00dflich vom \u201ealten Vorurteil vom b\u00f6sen Kommunismus\u201c. Man traut seinen Augen nicht.<br>Hatte die Welt nicht seit 1917 vor Augen, was ein kommunistisches System in der Realit\u00e4t bedeutete? Hatte der westliche Teil Europas nicht seit der Spaltung Europas vor Augen, was Kommunismus vor der Haust\u00fcr, im Falle Deutschlands mit Mauer und Schie\u00dfbefehl im eigenen Land bedeutet?<\/p>\n\n\n\n<p>Das System des sowjetischen GULAG, das ja nicht erst seit dem \u201eArchipel GULAG\u201c (1973 erschienen) von Solschenizyn bekannt war, bereits 1962 erschien sein \u201eEin Tag im Leben des Iwan Denissowitsch\u201c. Die Niederschlagung des Aufstandes 1953 in der DDR, die t\u00f6dlichen Schauprozesse in der Tschechoslowakei und anderen Staaten, die Niederschlagung des Ungarn-Aufstandes 1956, Chruschtschows Geheimrede 1956 mit der Aufdeckung der stalinschen Verbrechen bis hin zur Niederwalzung des Prager Fr\u00fchlings 1968 durch sowjetische Panzer.<\/p>\n\n\n\n<p>Alles nur fake-news, die das \u201eVorurteil gegen den b\u00f6sen Kommunismus\u201c und den Kampf gegen \u201elinks\u201c n\u00e4hrten, gab es nicht gen\u00fcgend Empirie um sich ein faktenorientiertes Urteil zum Thema Kommunismus zu bilden?<\/p>\n\n\n\n<ol start=\"3\" class=\"wp-block-list\">\n<li>Feindbild Helmut Kohl<\/li>\n<\/ol>\n\n\n\n<p>Herausragender Trigger ist f\u00fcr die Verfasserin Helmut Kohl, an dem sie sich \u00fcber weite Strecken geradezu obsessiv abarbeitet. Ihre abgrundtiefe Verachtung gegen den ehemaligen Bundeskanzler schreibt sie sich aus jeder journalistischen Pore.<\/p>\n\n\n\n<p>Nun kann man zu Kohl menschlich oder politisch stehen wie man will, ein Heiliger war er ebenso wenig wie wir selbst es sind.<\/p>\n\n\n\n<p>Seitens der Verfasserin gibt es aber offensichtlich ein anders gelagertes, mit dem eigentlichen Thema des Buches in keinem Zusammenhang stehendes Vorverst\u00e4ndnis und Aversionsfaktoren, die nicht offengelegt werden, die \u201eArgumentations\u201clinien des Buches jedoch grundieren und deutlich sp\u00fcrbar sind.<\/p>\n\n\n\n<p>Die Verfasserin geisselt die Formulierung Kohls von der \u201eGnade der sp\u00e4ten Geburt\u201c und zieht sie ins L\u00e4cherliche. Weil sie sie nicht verstanden hat oder bewu\u00dft missinterpretiert mag dahinstehen.<\/p>\n\n\n\n<p>Jedenfalls versucht die Verfasserin um diesen Ausspruch Kohls herum ein Narrativ zu entwickeln, wonach Kohl zum obersten strategischen Geschichtsrevisionisten der bundesrepublikanischen Geschichte d\u00e4monisiert wird.<\/p>\n\n\n\n<p>Den unionsgef\u00fchrten Bundesregierungen wird vorgeworfen, \u201edie Jahre zwischen 1933 und 1945 einebnen zu wollen\u201c. Der \u201esich christlich nennenden Union\u201c wird vorgeworfen, \u201enach alter Tradition T\u00e4ter und Opfer zu vertauschen\u201c. Die CDU habe lange Jahre gebraucht, \u201eum in den Verschw\u00f6rern keine Verr\u00e4ter mehr zu sehen\u201c.<br>Dass in den Reihen der Unionsparteien Politiker an f\u00fchrender Stelle waren, die im aktiven Widerstand waren und in Konzentrationslagern gesessen hatten wird schlichtweg ausgeblendet.<\/p>\n\n\n\n<p>Das ist starker Tobak und nicht nur eine Simplifizierung, das ist Geschichtsklitterung.<\/p>\n\n\n\n<p>Die Aversion gegen Kohl triftet dann ins Absurd-L\u00e4cherliche ab, wenn sich die Verfasserin seitenweise an seiner Entscheidung abarbeitet, die K\u00e4the-Kollwitz-Skulptur \u201eMutter mit totem Sohn\u201c ins Zentrum der Neuen Wache in Berlin als Gedenkst\u00e4tte f\u00fcr die \u201eOpfer von Krieg und Gewaltherrschaft\u201c zu stellen.<\/p>\n\n\n\n<p>Wenn ich vor dieser Skulptur stehe, denke ich nicht an Freisler als Opfer, sondern habe viele andere vor Augen. Und diese beeindruckende Skulptur der trauernden Mutter gibt diesem Leid Ausdruck.<br>Aber, so viel hat man aus den vorangegangen Seiten gelernt, da Kohl sich f\u00fcr diese Skulptur entschieden hat, taugt sie nat\u00fcrlich nicht f\u00fcr dieses Mahnmal. Man ist versucht, die Verfasserin darauf hinzuweisen, dass zumindest in diesem Falle f\u00fcr Kohl sprechen sollte, dass er die Skulptur einer sozialistischen K\u00fcnstlerin ausgew\u00e4hlt hat.<\/p>\n\n\n\n<p>Die \u201eKritik\u201c geht schliesslich sogar so weit zu monieren, dass die Statue um das F\u00fcnffache hatte vergr\u00f6\u00dfert werden m\u00fcssen. Was die Verfasserin wohl kritisiert h\u00e4tte, wenn man die Originalgr\u00f6\u00dfe der Statue beibehalten und diese sich in dem Raum verloren h\u00e4tte: Geringsch\u00e4tzung der K\u00fcnstlerin oder gar der Opfer und der Trauer um sie?<br>Diese Art von \u201eKritik\u201c ist schlichtweg nicht mehr ernst zu nehmen.<\/p>\n\n\n\n<ol start=\"4\" class=\"wp-block-list\">\n<li>\u00dcber diese beiden zentralen Aspekte hinaus g\u00e4be es eine ganze Reihe weiterer, die hinterfragt werden k\u00f6nnten, weil in der Darstellung verk\u00fcrzt, ausgeblendet oder schlicht unterkomplex behauptet wird.<\/li>\n<\/ol>\n\n\n\n<p>So mal schnell aus der H\u00fcfte geschossene Behauptungen wie, dass der Grundlagenvertrag zwischen der Bundesrepublik und der DDR von 1973 die \u201einternationalen Voraussetzungen f\u00fcr die Wiedervereinigung 1990 schuf\u201c. Da w\u00e4re ja wohl noch Vieles hinzuzuf\u00fcgen.<\/p>\n\n\n\n<p>Die Verfasserin ist schnell bei der Hand, andere zu kritisieren. Selbst Richard von Weizs\u00e4cker kommt mit seiner ber\u00fchmten Rede zum Rede zum 8. Mai 1945 nicht ungeschoren davon, denn er habe nicht alles gesagt.<br>Sie selbst hat jedoch keine Probleme damit, auch mal was wegzulassen. Sachverhalte werden verk\u00fcrzt dargestellt, aber Zuschreibungen vorgenommen. Sei es das Attentat auf Benno Ohnesorg 1967, seit Jahren weiss man, dass der Sch\u00fctze bei der Stasi unter Vertrag war. Sei es das gescheiterte Misstrauensvotum gegen Willy Brandt 1972, auch hier ist seit vielen Jahren bekannt, dass die Stasi Abgeordnete gekauft hatte, der damalige parlamentarische Gesch\u00e4ftsf\u00fchrer der SPD, Wienand, wurde 1996 wegen Spionage f\u00fcr die DDR verurteilt. Findet hier alles nur zur H\u00e4lfte statt.<\/p>\n\n\n\n<p>In diesen Kontext geh\u00f6rt dann auch die kritische Erw\u00e4hnung des Verbots der FDJ und der KPD in der Bundesrepublik. Eine klare und konsequente Entscheidung des Prinzips der \u201ewehrhaften Demokratie\u201c im Grundgesetz, eine Lektion aus der Weimarer Republik. Aber klar, ging ja \u201egegen links\u201c. Dass vier Jahre vor der KPD die SRP als Nachfolgepartei der NSDAP verboten wurde, ist der Verfasserin jedoch keine Erw\u00e4hnung wert. Passt es nicht ins Bild?<\/p>\n\n\n\n<p>Auch die Ableitungen ihrer vielfachen Generalisierungen sind schwierig nachzuvollziehen, da muss dann eine Wandschschmiererei oder ein Brief als Beleg herhalten.<\/p>\n\n\n\n<p>Die Verfasserin widerspricht sich noch auf den beiden letzten Seiten.<br>So ist der 20. Juli \u201eein Mythos, dem die Botschaft abhandengekommen ist\u201c. Wenige Zeilen weiter kommt in dem Attentatsversuch dann \u201eeine demokratische Qualit\u00e4t zum Ausdruck, die so etwas wie das unausgesprochene Verm\u00e4chtnis der Menschen im Widerstand ist\u201c. Ja, was denn nun?<\/p>\n\n\n\n<p>Ich habe dieses Buch um die Wochen des 20. Juli 2024 gelesen. In vielen Zeitungsbeitr\u00e4gen zum 80. Jahrestag des Attentats habe ich dabei mehr an kritischem Differenzierungsverm\u00f6gen gefunden als in diesen 400 Buchseiten.<\/p>\n\n\n\n<p>Zu Beginn habe ich \u201ebekannt\u201c, dass ich als Sch\u00fcler die Verschw\u00f6rer des 20. Juli bewundert habe, zugegeben, ohne all die Details und Differenzierungen zu kennen, die ja dann auch erst im Laufe der nachfolgenden Jahre und Jahrzehnte erarbeitet wurden.<br>An dieser Bewunderung hat sich dennoch nichts ge\u00e4ndert. Die Tat des 20. Juli bleibt als solche bestehen. Da muss man nichts mystifizieren, aber man muss auch nicht k\u00fcnstlich \u201eentheroisieren\u201c.<\/p>\n\n\n\n<p>Ich finde das Buch auch deshalb problematisch, weil es aufgrund dieser Undifferenziertheiten keinerlei Hilfestellung f\u00fcr die R\u00fcckkopplung des Themas zur aktuellen Entwicklung bietet.<br>Der anwachsende Rechtspopulismus\/Rechtsextremismus sollte doch dazu f\u00fchren differenziert vorzugehen, diesen Teil der deutschen Geschichte nicht durch die vereinnahmen oder pervertieren zu lassen, die enttabuisieren wollen und versuchen, bestimmte Grenzen in ihrer Alltagspolitik und -rhetorik zu verschieben, wie das ein politisch aktiver ehemaliger Geschichtslehrer in Th\u00fcringen oder angeklagte \u201eReichsb\u00fcrger\u201c in ihren Verteidigungsreden vor Gericht vorexerzieren. Es geht darum, sich mit allen Kr\u00e4ften gegen den Versuch dieser Kr\u00e4fte zu wenden, diesen Teil deutscher Geschichte in einem schon pathologischen Anfall von Geschichtszynismus zu kapern.<\/p>\n\n\n\n<p>Es bleibt eine gewisse Verwunderung, wie es dieses Buch auf die shortlist f\u00fcr den Deutschen Sachbuchpreis 2024 schaffen konnte und so hervorragende B\u00fccher wie beispielsweise die Kant-Biographie von Markus Willaschek damit konkurrieren mussten.<\/p>\n\n\n\n<p>Eine letzte editorische Anmerkung:<br>Die Kaufentscheidung zwischen hardcover oder ebook ist eine bewusste Auswahl-Entscheidung zwischen sehr unterschiedlichen Formaten. Erstmals habe ich es nun bei einem Sachbuch erlebt, dass man auf den Anmerkungsteil, (ein Literatur- oder Sachbegriffsverzeichnis gibt es nicht, nur einige Leseempfehlungen), nur mittels eines QR-Codes zugreifen kann. Ein solcher macht Sinn bei B\u00fcchern, in denen es um Musik und entsprechende Verweise auf Plattformen zum H\u00f6ren der Titel geht, (interessant gemacht in der Autobiographie von Klaus Doldinger, \u201emade in germany\u201c oder in Sergio de Molinos \u201eLos alemanes\u201c \u2013 Besprechung von \u201eLos alemanes\u201c demn\u00f6chst hier).<br>Bei diesem Buch ist ein solches Verfahren jedoch umst\u00e4ndlich und eine Zumutung, leserfreundlich ist etwas anderes.<br>Hoffentlich macht dieses schlechte Beispiel keine Schule!<\/p>\n\n\n\n<p>Ruth Hoffmann: Das deutsche Alibi \u2013 Mythos \u201eStauffenberg-Attentat \u2013 wie der 20. Juli 1944 verkl\u00e4rt und politisch instrumentalisiert wird<\/p>\n\n\n\n<p>ISBN -13 978-3442317226<\/p>\n<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger\" title=\"\" data-post-id=\"1896\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n                <\/a>\r\n    <span class=\"pld-like-count-wrap pld-count-wrap\">    <\/span>\r\n<\/div><div class=\"pld-dislike-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-dislike-trigger pld-like-dislike-trigger\" title=\"\" data-post-id=\"1896\" data-trigger-type=\"dislike\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                        <i class=\"fas fa-thumbs-down\"><\/i>\r\n                <\/a>\r\n    <span class=\"pld-dislike-count-wrap pld-count-wrap\"><\/span>\r\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Ich will mit einem \u201eBekenntnis\u201c beginnen. F\u00fcr mich waren als Sch\u00fcler Stauffenberg und die Beteiligten Helden. M\u00e4nner, die unter Einsatz ihres Lebens versucht hatten, einen der gr\u00f6\u00dften Verbrecher der Menschheitsgeschichte zu beseitigen, dabei scheiterten, und dennoch Gro\u00dfes und Beispielhaftes getan hatten. In diese Reihe geh\u00f6rten f\u00fcr mich auch die Geschwister Scholl und ihre Mitstreiter der \u201eWei\u00dfen Rose\u201c, \u201eder einsame Attent\u00e4ter\u201c (so ein Biographie &#8211; nTitel) Georg Elser oder der beeindruckende Dietrich Bonhoeffer, dessen wenige Monate vor seiner Hinrichtung in Pl\u00f6tzensee verfasstes Gebet \u201eVon guten M\u00e4chten\u201c mich bis heute begleitet. Wie h\u00e4tte Deutschland diese Menschen gebraucht! Sie waren und sind vermutlich bis heute f\u00fcr Viele die bekanntesten Pers\u00f6nlichkeiten des Widerstandes gegen Hitler. Je mehr man las, desto mehr erfuhr man jedoch \u00fcber die Breite des Widerstandes, die sehr unterschiedliche Herkunft von sich dem Regime entgegenstellenden Menschen, ihre Denkweise, ihre Motivationen, ihre Hoffnungen, ihre Ziele, ihre Erfolge, ihr Scheitern, ihr Sterben oder auch ihr \u00dcberleben. Zu meinen ersten beeindruckenden Leseerlebnissen z\u00e4hlt das Buch von Peter Hoffmann (Widerstand-Staatsstreich-Attentat), das mich regelrecht in Bann geschlagen hat. \u00dcber die Jahre erarbeitete die Forschung neue Erkenntnisse, schuf Raum f\u00fcr differierende Interpretationsans\u00e4tze und multiple Schwerpunktsetzungen. Insbesondere der Blick auf die milit\u00e4rischen Widerst\u00e4ndler, ihr Herkommen, ihre Denkungsart oder ihre anf\u00e4ngliche N\u00e4he zum nationalsozialistischen Regime wurde kritischer und erm\u00f6glichte ein immer realistischeres Bild der handelnden Personen und der Umst\u00e4nde.Die Verfasserin ist beileibe nicht die erste, die Hand an den \u201eMythos\u201c legt. Ich verweise nur auf die hervorragende Biographie Stauffenbergs von Thomas Karlauf (2019).Es entwickelte sich bei mir fr\u00fch ein Bewusstsein daf\u00fcr, dass es nicht immer nur die \u201eGro\u00dftaten\u201c waren, die erinnerungsw\u00fcrdig und beispielhaft sind. So setzte Hans Fallada in seinem 1947 erschienenem und heute noch lesenswerten Roman \u201eJeder stirbt f\u00fcr sich allein\u201c dem Ehepaar Hampel ein Denkmal. Die Biographie der deutschen Kommunistin Hertha Gordon-Walcher (\u201eBittere Brunnen\u201c), 2023 mit dem Preis der Leipziger Buchmesse ausgezeichnet, ist ein j\u00fcngstes Beispiel von in diesen Kontext geh\u00f6renden Lebensl\u00e4ufen. Das Thema l\u00e4sst die Deutschen offensichtlich nicht los, und das ist gut so. Die Geschichte des Widerstandes gegen Hitler d\u00fcrfte weitgehend erforscht sein. Wer sich \u00fcber die Jahre etwas intensiver mit dem Thema besch\u00e4ftigt hat, wird in \u201eDas deutsche Alibi\u201c nichts umst\u00fcrzend Neues finden. Aber es ist gut und wichtig, diesen Teil deutscher Geschichte f\u00fcr jede Generation immer wieder aufzugreifen und zu erz\u00e4hlen. Dies bietet die Chance, diesen Teil deutscher Geschichte an aktuelle Entwicklungen und Herausforderungen r\u00fcckzukoppeln. Raum f\u00fcr (neue) Interpretationen bleibt immer. Nun kann man, so der Ansatz des Buches, auch auf der Basis von reiner Quellenauswertung, d.h. der fachlichen und wissenschaftlichen Arbeit anderer, ein interessantes, anregendes Sachbuch mit neuen Erkenntnissen oder Interpretationsans\u00e4tzen schreiben. \u201eDas deutsche Alibi\u201c f\u00e4llt jedoch nicht in diese Kategorie. Zwar filtriert die Verfasserin aus ihrer Literaturschau eine ganze Reihe von zutreffenden, wenn auch bekannten Informationen heraus. Sei es die halbherzige und sp\u00e4te Aufarbeitung des Nationalsozalismus in der Fr\u00fchphase der Bundesrepublik, Schicksale wie die von Fritz Bauer, der sich um die Strafverfolgung von Nazi-Verbrechern verdient machte oder die Verengung der Widerstandsrezeption auf den milit\u00e4rischen Widerstand. Dennoch tat ich mir schwer mit diesem Buch. Aber nicht, weil es mir inhaltlich substantiell nichts Neues brachte. Es sind die Verallgemeinerungen, die Einseitigkeiten, offensichtliche Voreingenommenheiten, das Undifferenzierte, die Ausblendungen, eine vielfach allzu simple Argumentationsweise, das oftmals analytisch Unterkomplexe, die aufsto\u00dfen. Ich will mich auf einige wesentliche Kritikpunkte beschr\u00e4nken. Die Verfasserin kritisiert, dass der \u201elinke Widerstand\u201c nicht hinreichend ber\u00fccksichtigt wurde und wird. Das traf sicherlich vor allem in den Anfangsjahren der Bundesrepublik zu und wurde der Geschichte und dem Blutzoll, den viele von der politischen Linken zahlen mussten, nicht gerecht. Ich habe den gr\u00f6\u00dften Respekt vor dem Mut und der Haltung der Sozialdemokraten, die meisten kommunistischen Abgeordneten waren bereits verhaftet oder auf der Flucht, die im Reichstag gegen das Erm\u00e4chtigungsgesetz Hitlers gestimmt haben. Der Satz des Sozialdemokraten Otto Wels in seiner Rede am 23. M\u00e4rz 1933: \u201eFreiheit und Leben kann man uns nehmen, die Ehre nicht\u201c, hat seinen Platz in der deutschen Geschichte. Weitgehend zutreffend ist auch, dass in der \u00f6ffentlichen Perzeption \u00fcber viele Jahre der 20. Juli dominierte und viele andere Gruppen und Widerstandsformen \u00fcberlagerte. Wobei die \u201eWeisse Rose\u201c der Geschwister Scholl, sehr fr\u00fch ebenfalls ein markanter \u201eErinnerungsort\u201c der Widerstandsgeschichte, nun nicht dem milit\u00e4risch-adligen Widerstand zuzurechnen ist.Dabei gab es \u201eTausende andere Mutige, die viele Jahre vor dem 20. Juli 1944 ihr Leben f\u00fcr das riskiert hatten, was sie f\u00fcr richtig hielten\u201c. Dem ist nur zuzustimmen.Aber standen diese Gegner wirklich nur links, im Ernst? Es gab beispielsweise auch Politiker der katholischen Zentrumspartei ebenso wie aus anderen b\u00fcrgerlichen Parteien oder ziviligesellschaftlichen Organisationen, die im Widerstand waren, in Gef\u00e4ngnissen und Konzentrationslagern sa\u00dfen oder zu Tode gekommen sind. Skurril wird es, wenn die Verfasserin Kardinal H\u00f6ffner vorwirft, in einer Rede zum 8. Mai nichts zum katholischen Widerstand gesagt zu haben. Das w\u00e4re doch die Gelegenheit gewesen, in ihrem Buch ein kleines Kapitel darauf zu verwenden. Aber halt, der erste Widerstand kam ja nur von \u201elinks\u201c. Ein Pater Alfred Delp, ein Pater Rupert Mayer oder ein Andreas Hermes, um nur drei Namen zu nennen, finden sich daher im Personenverzeichnis dieses Buches nicht. Es sind solche undifferenzierten Verengungen, die ver\u00e4rgern und ein unzutreffendes, weil unvollst\u00e4ndiges Bild zeichnen. Ein zentrales Problem besteht im Verst\u00e4ndnis des Begriffes \u201eWiderstand\u201c. Ich will hier gar nicht in die Debatte einsteigen, welche Formen von Widerstand es geben mag. Es geht im Kern darum, gegen was oder wen Widerstand geleistet wurde, im Falle der Nazis gegen eine der schlimmsten Diktaturen in der Menschheitsgeschichte. Vor diesem Hintergrund sollte man in der Lage sein, sich gegen den Missbrauch des Begriffs \u201eWiderstand\u201c durch die Studentenbewegung 1968 zu wenden, die meinte, diesen Begriff f\u00fcr ihren Kampf gegen ein \u201efaschistisches Nachkriegsdeutschland\u201c okkupieren zu k\u00f6nnen. Diese mangelnde Differenzierung beim \u201eWogegen\u201c setzt sich dann fort bei der Debatte des \u201eWof\u00fcr\u201c Widerstand geleistet wurde. Ich habe vor jedem den tiefsten Respekt, der sich wie aktiv auch immer gegen das Nazi-Regime gestellt hat. Da spielt es f\u00fcr mich keine Rolle, ob jemand Kommunist, Gewerkschafter, Liberaler oder katholischer oder evangelischer Christ oder sonst was war. Dies umso mehr, als uns \u201eNachgeborenen\u201c etwas mehr Demut gut zu Gesicht<\/p>","protected":false},"author":1,"featured_media":1890,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[42],"tags":[106,73,104,103],"class_list":["post-1896","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-h","tag-20-juli-1944","tag-deutsche-geschichte-20-jahrhundert","tag-stauffenberg-attentat","tag-widerstand-gegen-hitler"],"_links":{"self":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/1896"}],"collection":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/comments?post=1896"}],"version-history":[{"count":4,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/1896\/revisions"}],"predecessor-version":[{"id":1900,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/1896\/revisions\/1900"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/media\/1890"}],"wp:attachment":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/media?parent=1896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/categories?post=1896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/tags?post=1896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}