{"id":1679,"date":"2024-08-17T18:09:54","date_gmt":"2024-08-17T18:09:54","guid":{"rendered":"https:\/\/buecher-books-libros.com\/?p=1679"},"modified":"2024-08-19T16:25:12","modified_gmt":"2024-08-19T16:25:12","slug":"vom-zauber-des-untergangs-was-pompeji-ueber-uns-erzaehlt","status":"publish","type":"post","link":"https:\/\/buecher-books-libros.com\/es\/z\/vom-zauber-des-untergangs-was-pompeji-ueber-uns-erzaehlt\/","title":{"rendered":"Vom Zauber des Untergangs. Was Pompeji \u00fcber uns erz\u00e4hlt."},"content":{"rendered":"<p>von Gabriel Zuchtriegel<\/p>\n\n\n\n<figure class=\"wp-block-image size-full is-resized\"><img fetchpriority=\"high\" decoding=\"async\" width=\"1366\" height=\"2428\" src=\"https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/04\/IMG_0278-scaled-e1713123500791.jpg\" alt=\"Strasse in Pompeji\" class=\"wp-image-1344\" style=\"width:354px;height:auto\"\/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>\u201cEs ist viel Unheil in der Welt geschehen, aber wenig, das den Nachkommen so viel Freude<br>gemacht h\u00e4tte\u201d. Mit diesen Worten fasste Goethe die Trag\u00f6die der kleinen, in der N\u00e4he von<br>Neapel liegenden Stadt Pompeji, die im Jahre 79 n. Chr. durch den Ausbruch des Vesuvs<br>ausgel\u00f6scht wurde, und die bis heute anhaltende Faszination dieser Geschichte und der<br>Wiederentdeckung Pompejis zusammen.<br>Mit dieser Geschichte befasst sich Gabriel Zuchtriegel, seit 2021 Direktor des<br>Arch\u00e4ologischen Parks Pompeji, eine damals h\u00f6chst umstrittene Ernennung.<br>Der Autor nimmt uns mit auf eine Zeitreise. Das Buch ist spannend geschrieben, man lernt<br>viel \u00fcber die griechisch \u2013 r\u00f6mische Antike, nat\u00fcrlich die Geschichte Pompejis und einige<br>seiner herausragenden Sehensw\u00fcrdigkeiten und die sich im Laufe der Zeit auch wandelnden<br>Erkenntnisse und Interpretationen.<br>Was sich in Pompeji allt\u00e4glich abspielt, sind \u201dAnn\u00e4herungsversuche an eine komplexe<br>Realit\u00e4t, die l\u00e4ngst vergangen ist\u201d. Pompeji erm\u00f6glicht einzigartige Einblicke in die antike<br>Lebenswelt und ist ein gelungenes Beispiel daf\u00fcr, wenn auch in dieser Form sicherlich selten<br>m\u00f6glich, was au\u00dferhalb eines rein musealen Elfenbeinturms an Darstellungs- und<br>Vermittlungsformen alles m\u00f6glich ist.<br>Das Faszinierende f\u00fcr Wissenschaftler und die Besucher von Pompeji liegt darin, dass dieses<br>weitl\u00e4ufige, aber noch lange nicht v\u00f6llig erschlossene Areal nicht einen sekund\u00e4ren Kontext<br>wie in einem normalen Museum abbildet, sondern direktes Erleben m\u00f6glich macht, da diese<br>\u201c Stadt gleichsam eingefroren\u201d vor einem liegt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large is-resized\"><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/04\/Pompeji-Leichnam-2-1024x768.jpeg\" alt=\"\" class=\"wp-image-1485\" style=\"width:533px;height:auto\" srcset=\"https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/04\/Pompeji-Leichnam-2-1024x768.jpeg 1024w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/04\/Pompeji-Leichnam-2-300x225.jpeg 300w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/04\/Pompeji-Leichnam-2-768x576.jpeg 768w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/04\/Pompeji-Leichnam-2-1536x1152.jpeg 1536w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/04\/Pompeji-Leichnam-2-16x12.jpeg 16w, https:\/\/buecher-books-libros.com\/wp-content\/uploads\/2024\/04\/Pompeji-Leichnam-2.jpeg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"has-text-align-left\"><br>Pompeji ist wie ein \u201eRiss in der Leinwand, durch den wir die M\u00f6glichkeit haben, einen Blick<br>hinter die offizielle Version der Geschichte zu werfen\u201c. Zuchtriegel weist darauf hin, dass die<br>\u201c\u00dcberlieferungsgeschichte\u201c stark durch \u201cdie Welt der Superreichen und M\u00e4chtigen<br>dominiert\u201d ist, denn: \u201eArme schreiben selten Tageb\u00fccher\u201d. Pompeji durchbricht dieses<br>Muster und erm\u00f6glicht vielgestaltige Einblicke in die Alltagswelt der untergegangenen Stadt.<br>Interessant sind auch die kritischen Anmerkungen Zuchtriegels zur universit\u00e4ren Ausbildung<br>und dem Wissenschaftsbetrieb der eigenen Zunft. Dieser selbstkritische Abstand ist wichtig,<br>um gerade das Arbeiten in einem herausfordernden Kontext wie dem Arch\u00e4ologischen Park<br>Pompeji zu erm\u00f6glichen.<br>Nachvollziehbar, aber f\u00fcr den Laien sicherlich zun\u00e4chst neu ist die Aussage, dass die<br>eigentliche Entdeckung teilweise erst lange nach der Ausgrabung selbst stattfindet, wenn die<br>Wissenschaftler in ihrer Arbeit fortgeschritten sind. Es ist hoch spannend zu verfolgen, was<br>die Arch\u00e4ologen beispielsweise aus einer knapp vierzeiligen Inschrift alles herauslesen. Dass<br>sich dabei \u00fcber die Jahre und Jahrzehnte nat\u00fcrlich auch modifizierende, sich<br>widersprechende, strittige Interpretationen herausbilden geh\u00f6rt zur Wissenschaftswelt<br>hinzu und wird an einigen Beispielen veranschaulicht.<br>Der Untertitel des Buches erschlie\u00dft sich mir nach der Lekt\u00fcre des Buches ehrlich gesagt<br>nicht so ganz. Allerdings lautet ein sch\u00f6ner und nachdenkenswerter Satz des Buches, der die<br>Br\u00fccke zu diesem Untertitel schlagen k\u00f6nnte: \u201dSetzt die Priorit\u00e4ten in Eurem Leben im<br>Bewusstsein seiner Endlichkeit\u201d.<br>Pompeji stand seit vielen Jahren auf der Liste der Dinge, die ich gerne sehen wollte. Aber wie<br>das so ist im Leben, Manches braucht seine Zeit. Dass sich dann das Erscheinen dieses<br>Buches und die M\u00f6glichkeit, Pompeji zu besuchen, zeitlich so exakt \u00fcberschnitten haben,<br>war f\u00fcr mich wirklich ein Gl\u00fccksfall.<br>Pompeji ist beeindruckend, ja erschlagend, aber in einem positiven Sinne. Meine Tochter,<br>die gerade ihren Uni Abschluss gemacht hatte, fragte mich beim Verlassen des Gel\u00e4ndes:<br>\u201ePapa, finanzierst du mir noch ein Studium der Arch\u00e4ologie?\u201c Das war nicht nur scherzhaft<br>gemeint. Die Antwort steht noch aus.<br>Die Geschichte, die Entdeckung Pompejis gehen weiter. Vor wenigen Wochen wurde ein<br>neues Haus mit verschiedenen S\u00e4len und pr\u00e4chtigen Fresken entdeckt. Ein besonders<br>sch\u00f6nes zeigt die Seherin Kassandra zusammen mit dem griechischen Gott Apollon.<br>Pompeji ist und bleibt spannend, ein Besuch wird angesichts neuer Entdeckungen immer<br>wieder lohnenswert sein.<br>\u201ePompeji\u201c wird von Zuchtriegel auch als Entwicklungsprojekt im Kontext der Region<br>Campania verstanden. Interessant ist die Darstellung der Projekte der Direktion, vor allem<br>Jugendliche zum Beispiel \u00fcber Theaterarbeit mit einzubinden und mit Ihnen zusammen ihren<br>\u201eSogno di volare\u201c, den \u201eTraum vom Fliegen\u201c, d.h. dem Ziel, ihren prek\u00e4ren<br>Lebensbedingungen zu entkommen, zu tr\u00e4umen und zu verwirklichen.<br>Das Buch, das auch einen ansprechenden Bildteil enth\u00e4lt, hat mehrere Auflagen erreicht, ist<br>inzwischen auch als Taschenbuch erh\u00e4ltlich und aktuell sicherlich der beste Reisef\u00fchrer f\u00fcr<br>Pompeji.<\/p>\n\n\n\n<p><br>Zum Abschluss noch ein Hinweis. Im Suhrkamp Verlag ist ein opulenter Bildband erschienen,<br>fast 500 Seiten stark: \u201ePompeji. Eine Reise durch die ber\u00fchmteste St\u00e4tte der klassischen<br>Antike\u201c. Angesichts des stolzen Preises von 150 \u20ac steht dieser Band leider nicht bei mir im<br>Regal. Aber es lohnt sich, beim n\u00e4chsten Besuch in der Buchhandlung diesen Band mal in die<br>Hand zu nehmen.<\/p>\n<div class=\"pld-like-dislike-wrap pld-template-1\">\r\n    <div class=\"pld-like-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-like-trigger pld-like-dislike-trigger\" title=\"\" data-post-id=\"1679\" data-trigger-type=\"like\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                        <i class=\"fas fa-thumbs-up\"><\/i>\r\n                <\/a>\r\n    <span class=\"pld-like-count-wrap pld-count-wrap\">1    <\/span>\r\n<\/div><div class=\"pld-dislike-wrap  pld-common-wrap\">\r\n    <a href=\"javascript:void(0)\" class=\"pld-dislike-trigger pld-like-dislike-trigger\" title=\"\" data-post-id=\"1679\" data-trigger-type=\"dislike\" data-restriction=\"cookie\" data-already-liked=\"0\">\r\n                        <i class=\"fas fa-thumbs-down\"><\/i>\r\n                <\/a>\r\n    <span class=\"pld-dislike-count-wrap pld-count-wrap\"><\/span>\r\n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>von Gabriel Zuchtriegel \u201cEs ist viel Unheil in der Welt geschehen, aber wenig, das den Nachkommen so viel Freudegemacht h\u00e4tte\u201d. Mit diesen Worten fasste Goethe die Trag\u00f6die der kleinen, in der N\u00e4he vonNeapel liegenden Stadt Pompeji, die im Jahre 79 n. Chr. durch den Ausbruch des Vesuvsausgel\u00f6scht wurde, und die bis heute anhaltende Faszination dieser Geschichte und derWiederentdeckung Pompejis zusammen.Mit dieser Geschichte befasst sich Gabriel Zuchtriegel, seit 2021 Direktor desArch\u00e4ologischen Parks Pompeji, eine damals h\u00f6chst umstrittene Ernennung.Der Autor nimmt uns mit auf eine Zeitreise. Das Buch ist spannend geschrieben, man lerntviel \u00fcber die griechisch \u2013 r\u00f6mische Antike, nat\u00fcrlich die Geschichte Pompejis und einigeseiner herausragenden Sehensw\u00fcrdigkeiten und die sich im Laufe der Zeit auch wandelndenErkenntnisse und Interpretationen.Was sich in Pompeji allt\u00e4glich abspielt, sind \u201dAnn\u00e4herungsversuche an eine komplexeRealit\u00e4t, die l\u00e4ngst vergangen ist\u201d. Pompeji erm\u00f6glicht einzigartige Einblicke in die antikeLebenswelt und ist ein gelungenes Beispiel daf\u00fcr, wenn auch in dieser Form sicherlich seltenm\u00f6glich, was au\u00dferhalb eines rein musealen Elfenbeinturms an Darstellungs- undVermittlungsformen alles m\u00f6glich ist.Das Faszinierende f\u00fcr Wissenschaftler und die Besucher von Pompeji liegt darin, dass diesesweitl\u00e4ufige, aber noch lange nicht v\u00f6llig erschlossene Areal nicht einen sekund\u00e4ren Kontextwie in einem normalen Museum abbildet, sondern direktes Erleben m\u00f6glich macht, da diese\u201c Stadt gleichsam eingefroren\u201d vor einem liegt. Pompeji ist wie ein \u201eRiss in der Leinwand, durch den wir die M\u00f6glichkeit haben, einen Blickhinter die offizielle Version der Geschichte zu werfen\u201c. Zuchtriegel weist darauf hin, dass die\u201c\u00dcberlieferungsgeschichte\u201c stark durch \u201cdie Welt der Superreichen und M\u00e4chtigendominiert\u201d ist, denn: \u201eArme schreiben selten Tageb\u00fccher\u201d. Pompeji durchbricht diesesMuster und erm\u00f6glicht vielgestaltige Einblicke in die Alltagswelt der untergegangenen Stadt.Interessant sind auch die kritischen Anmerkungen Zuchtriegels zur universit\u00e4ren Ausbildungund dem Wissenschaftsbetrieb der eigenen Zunft. Dieser selbstkritische Abstand ist wichtig,um gerade das Arbeiten in einem herausfordernden Kontext wie dem Arch\u00e4ologischen ParkPompeji zu erm\u00f6glichen.Nachvollziehbar, aber f\u00fcr den Laien sicherlich zun\u00e4chst neu ist die Aussage, dass dieeigentliche Entdeckung teilweise erst lange nach der Ausgrabung selbst stattfindet, wenn dieWissenschaftler in ihrer Arbeit fortgeschritten sind. Es ist hoch spannend zu verfolgen, wasdie Arch\u00e4ologen beispielsweise aus einer knapp vierzeiligen Inschrift alles herauslesen. Dasssich dabei \u00fcber die Jahre und Jahrzehnte nat\u00fcrlich auch modifizierende, sichwidersprechende, strittige Interpretationen herausbilden geh\u00f6rt zur Wissenschaftswelthinzu und wird an einigen Beispielen veranschaulicht.Der Untertitel des Buches erschlie\u00dft sich mir nach der Lekt\u00fcre des Buches ehrlich gesagtnicht so ganz. Allerdings lautet ein sch\u00f6ner und nachdenkenswerter Satz des Buches, der dieBr\u00fccke zu diesem Untertitel schlagen k\u00f6nnte: \u201dSetzt die Priorit\u00e4ten in Eurem Leben imBewusstsein seiner Endlichkeit\u201d.Pompeji stand seit vielen Jahren auf der Liste der Dinge, die ich gerne sehen wollte. Aber wiedas so ist im Leben, Manches braucht seine Zeit. Dass sich dann das Erscheinen diesesBuches und die M\u00f6glichkeit, Pompeji zu besuchen, zeitlich so exakt \u00fcberschnitten haben,war f\u00fcr mich wirklich ein Gl\u00fccksfall.Pompeji ist beeindruckend, ja erschlagend, aber in einem positiven Sinne. Meine Tochter,die gerade ihren Uni Abschluss gemacht hatte, fragte mich beim Verlassen des Gel\u00e4ndes:\u201ePapa, finanzierst du mir noch ein Studium der Arch\u00e4ologie?\u201c Das war nicht nur scherzhaftgemeint. Die Antwort steht noch aus.Die Geschichte, die Entdeckung Pompejis gehen weiter. Vor wenigen Wochen wurde einneues Haus mit verschiedenen S\u00e4len und pr\u00e4chtigen Fresken entdeckt. Ein besonderssch\u00f6nes zeigt die Seherin Kassandra zusammen mit dem griechischen Gott Apollon.Pompeji ist und bleibt spannend, ein Besuch wird angesichts neuer Entdeckungen immerwieder lohnenswert sein.\u201ePompeji\u201c wird von Zuchtriegel auch als Entwicklungsprojekt im Kontext der RegionCampania verstanden. Interessant ist die Darstellung der Projekte der Direktion, vor allemJugendliche zum Beispiel \u00fcber Theaterarbeit mit einzubinden und mit Ihnen zusammen ihren\u201eSogno di volare\u201c, den \u201eTraum vom Fliegen\u201c, d.h. dem Ziel, ihren prek\u00e4renLebensbedingungen zu entkommen, zu tr\u00e4umen und zu verwirklichen.Das Buch, das auch einen ansprechenden Bildteil enth\u00e4lt, hat mehrere Auflagen erreicht, istinzwischen auch als Taschenbuch erh\u00e4ltlich und aktuell sicherlich der beste Reisef\u00fchrer f\u00fcrPompeji. Zum Abschluss noch ein Hinweis. Im Suhrkamp Verlag ist ein opulenter Bildband erschienen,fast 500 Seiten stark: \u201ePompeji. Eine Reise durch die ber\u00fchmteste St\u00e4tte der klassischenAntike\u201c. Angesichts des stolzen Preises von 150 \u20ac steht dieser Band leider nicht bei mir imRegal. Aber es lohnt sich, beim n\u00e4chsten Besuch in der Buchhandlung diesen Band mal in dieHand zu nehmen. 1<\/p>","protected":false},"author":1,"featured_media":1344,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[60],"tags":[77,83,76],"class_list":["post-1679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-z","tag-archaeologie","tag-italien","tag-pompeji"],"_links":{"self":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/1679"}],"collection":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/comments?post=1679"}],"version-history":[{"count":2,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/1679\/revisions"}],"predecessor-version":[{"id":1681,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/posts\/1679\/revisions\/1681"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/media\/1344"}],"wp:attachment":[{"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/media?parent=1679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/categories?post=1679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/buecher-books-libros.com\/es\/wp-json\/wp\/v2\/tags?post=1679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}